{"id":9841,"date":"2025-05-26T17:07:02","date_gmt":"2025-05-26T17:07:02","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=9841"},"modified":"2025-05-28T17:01:58","modified_gmt":"2025-05-28T17:01:58","slug":"mountain-bike-sancalar-julian-corso-vencedor-en-santiago-del-estero","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/05\/26\/mountain-bike-sancalar-julian-corso-vencedor-en-santiago-del-estero\/","title":{"rendered":"MOUNTAIN BIKE \u2013 SANCALAR: JULI\u00c1N CORZO, VENCEDOR EN SANTIAGO DEL ESTERO"},"content":{"rendered":"<p style=\"text-align: justify;\">Nueva fecha del regional, que se llev\u00f3 a cabo este domingo, con la presencia de pedalistas chilecite\u00f1os.<br \/>\nJuli\u00e1n Corso, en la categor\u00eda Cadetes tuvo una muy buena actuaci\u00f3n, ya que fue ganador de la categor\u00eda en el XCO, y fue segundo en la especialidad del XCC short track.<br \/>\nEn tanto que Mateo Fajardo en la categor\u00eda Infantiles B fue tercero, con una correcta actuaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva fecha del regional, que se llev\u00f3 a cabo este domingo, con la presencia de pedalistas chilecite\u00f1os. Juli\u00e1n Corso, en&hellip;<\/p>\n","protected":false},"author":2,"featured_media":9842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9841"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9842"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}