{"id":9782,"date":"2025-05-25T01:33:53","date_gmt":"2025-05-25T01:33:53","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=9782"},"modified":"2025-05-25T01:33:53","modified_gmt":"2025-05-25T01:33:53","slug":"huracan-por-penales-le-gano-al-rojo-en-avellaneda-y-esta-en-la-final-del-torneo-apertura","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/05\/25\/huracan-por-penales-le-gano-al-rojo-en-avellaneda-y-esta-en-la-final-del-torneo-apertura\/","title":{"rendered":"HURAC\u00c1N POR PENALES LE GAN\u00d3 AL ROJO EN AVELLANEDA, Y EST\u00c1 EN LA FINAL DEL TORNEO APERTURA"},"content":{"rendered":"<p style=\"text-align: justify;\">El Globo se impuso 6-5 en Avellaneda desde los doce pasos tras haber igualado sin goles en los 90 minutos.<!--more--><\/p>\n<p style=\"text-align: justify;\">HURAC\u00c1N dio un nuevo golpe y elimin\u00f3 a Independiente en Avellaneda. Tras haber igualado sin goles en tiempo reglamentario, el Globo se impuso 6-5 por penales en una definici\u00f3n apasionante y jugar\u00e1 la final del Torneo Apertura. El domingo 1\u00b0 de junio buscar\u00e1 el t\u00edtulo en Santiago del Estero ante San Lorenzo o Platense.<br \/>\nEn un primer tiempo marcado por la pierna fuerte, el Rojo se hizo de la posesi\u00f3n de la pelota, pero no por eso evit\u00f3 sufrir los ataques directos del Globo.<br \/>\nRodrigo Rey evit\u00f3 la apertura del marcador tras un cabezazo de Walter Mazzanti y el local respondi\u00f3 con un desborde y centro de Diego Tarzia, que Hern\u00e1n Gal\u00edndez lleg\u00f3 a manotear y nadie de Independiente alcanz\u00f3 a empujar.<br \/>\nEn el cierre de la primera parte, Tarzia cay\u00f3 dentro del \u00e1rea tras disputar una pelota con Fabio Pereyra y todo el estadio reclam\u00f3 penal, pero Mastr\u00e1ngelo no sancion\u00f3. La repetici\u00f3n de la transmisi\u00f3n, le dio la raz\u00f3n al refer\u00ed.<br \/>\nLa segunda mitad comenz\u00f3 con el mismo desarrollo: Matko Miljevic exigi\u00f3 a Rey con un remate desde la puerta del \u00e1rea y Gal\u00edndez se luci\u00f3 ante una tijera de Mat\u00edas Gim\u00e9nez.<br \/>\nA falta de quince minutos, el arquero del Rojo se visti\u00f3 de h\u00e9roe. Pereyra, de palomita, cabece\u00f3 una pelota parada ejecutada por Miljevic y Rey con su mano izquierda evit\u00f3 el gol de la visita.<br \/>\nIndependiente reaccion\u00f3 r\u00e1pidamente y Luciano Cabral tuvo en sus pies el 1-0. El 10 del Rey de Copas remat\u00f3 cruzado y su tiro sali\u00f3 apenas desviado.<br \/>\nSin diferencias en los 90 minutos, la definici\u00f3n se traslad\u00f3 a la tanda de penales. All\u00ed Gabriel \u00c1valos abri\u00f3 la tanda con un remate al travesa\u00f1o, Hurac\u00e1n se puso 4-3 arriba y el Colo Gil tuvo la clasificaci\u00f3n en sus pies, pero Rey se qued\u00f3 parado en el medio y le contuvo el disparo. Lom\u00f3naco y Angulo marcaron luego para Independiente y Pereyra y Mazzantti para adelantar 6-5 al Globo. Gal\u00edndez se qued\u00f3 con la ejecuci\u00f3n de Hidalgo y liquid\u00f3 la serie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Globo se impuso 6-5 en Avellaneda desde los doce pasos tras haber igualado sin goles en los 90 minutos.<\/p>\n","protected":false},"author":2,"featured_media":9783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9782"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9783"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}