{"id":9711,"date":"2025-05-21T00:15:46","date_gmt":"2025-05-21T00:15:46","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=9711"},"modified":"2025-05-23T14:54:06","modified_gmt":"2025-05-23T14:54:06","slug":"futbol-torneo-provincial-sortearon-las-semifinales","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/05\/21\/futbol-torneo-provincial-sortearon-las-semifinales\/","title":{"rendered":"F\u00daTBOL \u2013 TORNEO PROVINCIAL: SORTEARON LAS SEMIFINALES"},"content":{"rendered":"<p style=\"text-align: justify;\">Se realiz\u00f3 el sorteo para las semifinales del provincial de clubes de primera.<!--more--><br \/>\nChacarita deber\u00e1 recibir a San Francisco de Capital el domingo 1 de junio, y la revancha despu\u00e9s en Capital. Mientras que Alto Valle de Olta ser\u00e1 local en el partido de ida ante San Mart\u00edn de Ulapes.<br \/>\nEste martes se realiz\u00f3 en sede de la Federaci\u00f3n Riojana el sorteo de cara a las semifinales del torneo provincial de clubes.<br \/>\nPor razones de p\u00fablico conocimiento, \u00e9ste fin de semana en Arauco se vivir\u00e1 la celebraci\u00f3n de la Fiesta Nacional de la Olivicultura, y por ello, reci\u00e9n inicia la definici\u00f3n de semifinales el domingo 1 de junio.<br \/>\nMientras que Alto Valle y San Mart\u00edn, podr\u00edan jugar \u00e9ste fin de semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se realiz\u00f3 el sorteo para las semifinales del provincial de clubes de primera.<\/p>\n","protected":false},"author":2,"featured_media":9712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provinciales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9711"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9711\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9712"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}