{"id":9669,"date":"2025-05-21T00:07:05","date_gmt":"2025-05-21T00:07:05","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=9669"},"modified":"2025-05-22T17:24:44","modified_gmt":"2025-05-22T17:24:44","slug":"futbol-femenino-los-newells-el-santo-y-defensores-ganaron-en-la-primera-fecha","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/05\/21\/futbol-femenino-los-newells-el-santo-y-defensores-ganaron-en-la-primera-fecha\/","title":{"rendered":"F\u00daTBOL FEMENINO: LOS NEWELL\u00b4S, EL SANTO, DEFE Y LOS CHUYOS, TRIUNFARON  EN LA PRIMERA FECHA"},"content":{"rendered":"<p style=\"text-align: justify;\">Jornada inaugural del campeonato de la Liga Chilecite\u00f1a temporada 2025. Este martes completan Los Chuyos ante Anguin\u00e1n.<!--more--><\/p>\n<p style=\"text-align: justify;\">Cinco de los seis partidos del f\u00fatbol femenino de la 1\u00b0 fecha del campeonato de la Liga Chilecite\u00f1a de F\u00fatbol se jugaron este pasado fin de semana. De local, las chicas de San Buenaventura en Vichigasta derrotaron por 1 a 0 a su par de Uni\u00f3n de Malligasta, en tanto que fue empate en Nonogasta entre J.V.Gonzalez y Atl\u00e9tico Chilecito, con el resultado de 0 a 0.<br \/>\nEn tanto que hubo tres victorias del visitante en esta fecha inaugural del torneo, Newell\u00b4s de Sa\u00f1ogasta venci\u00f3 por 1 a 0 a Independiente, en tanto que Defensores de la Plata le gan\u00f3 2 a 1 a Estrella Roja, y las actuales campeonas de Newell\u00b4s de Chilecito derrotaron por 3 a 1 a Los Andes.<br \/>\nPor su parte, el martes completaron, Los Chuyos de local se impuso 3 a 2 al elenco de Anguin\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jornada inaugural del campeonato de la Liga Chilecite\u00f1a temporada 2025. Este martes completan Los Chuyos ante Anguin\u00e1n.<\/p>\n","protected":false},"author":2,"featured_media":9670,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9669"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9670"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}