{"id":9647,"date":"2025-05-19T02:56:42","date_gmt":"2025-05-19T02:56:42","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=9647"},"modified":"2025-05-19T14:19:18","modified_gmt":"2025-05-19T14:19:18","slug":"jazz-ortenzi-campeona-en-suecia","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/05\/19\/jazz-ortenzi-campeona-en-suecia\/","title":{"rendered":"JAZZ ORTENZI, CAMPEONA EN SUECIA"},"content":{"rendered":"<p style=\"text-align: justify;\">La chilecite\u00f1a venci\u00f3 en la final a la espa\u00f1ola Irene Burillo por 6\/4 y 6\/2 y se qued\u00f3 con el t\u00edtulo en el W35 de Bastad, sumando su primer t\u00edtulo del a\u00f1o.<!--more--><\/p>\n<p style=\"text-align: justify;\">Jazm\u00edn Ortenzi le puso el broche de oro a una semana perfecta, en el inicio de la gira europea dentro del Circuito Profesional de Tenis, ya que este domingo se coron\u00f3 como campeona en el Torneo 35 de Bastad, Suecia.<br \/>\nDe esta manera, la chilecite\u00f1a de 23 a\u00f1os logr\u00f3 su primer t\u00edtulo de la temporada, el und\u00e9cimo de su carrera y tambi\u00e9n el primero en esta categor\u00eda, ya que todos los anteriores hab\u00edan sido en W15.<br \/>\nEn la final del certamen sueco, que reparti\u00f3 30 mil d\u00f3lares en premios y puntos para el ranking WTA, Ortenzi (248\u00b0 WTA y cuarta favorita), venci\u00f3 en sets consecutivos a la espa\u00f1ola Irene Burillo (quinta favorita, 255 WTA), a quien derrot\u00f3 por 6\/4 y 6\/2 en 1 hora y 65 minutos de juego, mostrando un juego s\u00f3lido y contundente, dejando sin opciones a su rival.<br \/>\nAs\u00ed, sum\u00f3 los cinco triunfos en la semana que le permitieron llegar al t\u00edtulo, recordando que en las fases previas elimin\u00f3 a la marroqu\u00ed Yasmine Kabbaj (2\/6, 6\/4 y 6\/0 en semifinales), a la turca Ipek Oz (7\/5 y 6\/2 en cuartos de final), a la local Lea Nilsson (6\/3 y 6\/1 en segunda ronda) y a la alemana Antonia Schmidt (6\/4, 5\/7 y 6\/3 en primera ronda).<br \/>\nCon esta consagraci\u00f3n, la riojana pudo cortar la racha de finales perdidas, ya que hab\u00eda ca\u00eddo en la definici\u00f3n de los dos W35 de Buenos Aires (con Luisina Giovanini y con la brasile\u00f1a Carolina Alves, respectivamente), en el W35 de Piracicaba (Brasil) donde perdi\u00f3 en la final con la italiana Giogia Pedone, y en la definici\u00f3n del W50 de Arequipa (Per\u00fa) donde hab\u00eda ca\u00eddo ante la francesa Tiantsoa Rakotomanga.<br \/>\nAdem\u00e1s, con la victoria ante la espa\u00f1ola Burillo, suma 30 partidos en el a\u00f1o, con 22 triunfos y 8 derrotas dentro del Circuito ITF, sin contar su participaci\u00f3n con la selecci\u00f3n nacional en la Billie Jean King Cup, donde logr\u00f3 4 victorias en 5 partidos.<\/p>\n<p style=\"text-align: justify;\"><strong>Pr\u00f3ximo destino: Eslovenia<\/strong><br \/>\nCasi sin tiempo para festejar, Jazm\u00edn Ortenzi emprendi\u00f3 viaje a Eslovenia, donde a partir del mi\u00e9rcoles jugar\u00e1 su segundo torneo en tierras europeas. Ser\u00e1 el W50 de Portoroz, ciudad ubicada en la zona balnearia del pa\u00eds, donde es la m\u00e1xima candidata al t\u00edtulo.<br \/>\nDespu\u00e9s de ahi viajar\u00e1 a Italia, donde disputar\u00e1 dos cert\u00e0menes consecutivos de mayor jerarqu\u00eda, ya que estar\u00e1 presente en el W75 de Brescia y en el W75 de Caserta, donde por el momento deber\u00e1 jugar las qualys para poder ingresar al cuadro principal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chilecite\u00f1a venci\u00f3 en la final a la espa\u00f1ola Irene Burillo por 6\/4 y 6\/2 y se qued\u00f3 con el&hellip;<\/p>\n","protected":false},"author":2,"featured_media":9667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9647"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9667"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}