{"id":9638,"date":"2025-05-18T18:23:15","date_gmt":"2025-05-18T18:23:15","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=9638"},"modified":"2025-05-18T18:24:27","modified_gmt":"2025-05-18T18:24:27","slug":"futbol-acto-de-inauguracion-de-la-cancha-del-club-atletico-los-chuyos-y-del-campeonato-2025-de-la-liga-chilecitena","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/05\/18\/futbol-acto-de-inauguracion-de-la-cancha-del-club-atletico-los-chuyos-y-del-campeonato-2025-de-la-liga-chilecitena\/","title":{"rendered":"F\u00daTBOL: ACTO DE INAUGURACI\u00d3N DE LA CANCHA DEL CLUB ATL\u00c9TICO LOS CHUYOS, Y DEL CAMPEONATO 2025 DE LA LIGA CHILECITE\u00d1A"},"content":{"rendered":"<p>D\u00edas hist\u00f3rico para la entidad Tricolor con estreno de su propio campo de juego. <!--more--><\/p>\n<p style=\"text-align: justify;\">Este s\u00e1bado 17 de mayo, en la previa al partido Los Chuyos vs. Anguin\u00e1n, se realiz\u00f3 la inauguraci\u00f3n del campeonato 2025 de la LCHF, con la presencia de autoridades de la Liga, representantes con delegaciones de los restantes clubes, y autoridades del Gobierno Municipal.<br \/>\nCampeonato 2025 que es denominado Edgard \u201cNegro\u201d Ju\u00e1rez en homenaje al ex dirigente de Defensores de la Plata fallecido recientemente, estuvo presente la familia, y tambi\u00e9n la denominaci\u00f3n del torneo Te\u00f3filo Su\u00e1rez, ex dirigente de Los Andes y de la Liga, que estuvo presente en el predio.<br \/>\nDe parte de la comisi\u00f3n directiva de Los Chuyos, hubo descubrimiento de placas en homenaje a los socios fundadores, y los socios que donaron el terreno para la construcci\u00f3n de la flamante cancha, y homenaje a los jugadores Pablo P\u00e1ez y Adri\u00e1n Carrizo, quienes estuvieron en el 2003 en el primer campeonato del club en la Liga, y hoy todavia juegan en la primera divisi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00edas hist\u00f3rico para la entidad Tricolor con estreno de su propio campo de juego.<\/p>\n","protected":false},"author":2,"featured_media":9639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9638"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9639"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}