{"id":9599,"date":"2025-05-16T14:36:44","date_gmt":"2025-05-16T14:36:44","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=9599"},"modified":"2025-05-16T14:36:44","modified_gmt":"2025-05-16T14:36:44","slug":"en-suecia-ortenzi-gana-y-avanzo-a-semifinales","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/05\/16\/en-suecia-ortenzi-gana-y-avanzo-a-semifinales\/","title":{"rendered":"EN SUECIA, ORTENZI GANA Y AVANZ\u00d3 A SEMIFINALES"},"content":{"rendered":"<p style=\"text-align: justify;\">La chilecite\u00f1a venci\u00f3 a la turca Ipek Oz por 7\/5 y 6\/2 y avanz\u00f3 en el W35 de Bastad, donde este s\u00e1bado buscar\u00e1 su lugar en la final.<!--more--><\/p>\n<p style=\"text-align: justify;\">Jazm\u00edn Ortenzi dio otro s\u00f3lido paso en el primer torneo de su presente gira por Europa, ya que este viernes volvi\u00f3 a ganar y por lo tanto se meti\u00f3 en las semifinales del Torneo W35 de Bastad, Suecia.<br \/>\nEn uno de los duelos correspondientes a los cuartos de final, Ortenzi (cuarta favorita, 248\u00ba WTA) derrot\u00f3 en sets corridos a las turca Ipek Oz (333\u00ba WTA), a quien le gan\u00f3 por 7\/5 y 6\/2.<\/p>\n<p style=\"text-align: justify;\">En el marco de un arranque de partido muy parejo y peleado, la chilecite\u00f1a de 23 a\u00f1os pudo imponerse en los momentos claves del primer set, que tuvo una duraci\u00f3n de casi 1 hora y media.<br \/>\nDesde all\u00ed, el partido se simplific\u00f3 para Ortenzi, que domin\u00f3 en el segundo set, impuso las condiciones del juego y cerr\u00f3 el triunfo con mucha solidez.<br \/>\nDe esta manera avanz\u00f3 a las semifinales, donde este s\u00e1bado se enfrentar\u00e1 ante la marroqu\u00ed Yasmine Kabba (816 WTA), que en el duelo de cuartos de final le gan\u00f3 por 6\/2 y 6\/3 a la rusa Anastasia Tikhonova.<br \/>\nAdem\u00e1s, la australiana Jaimee Fourlis derrot\u00f3 a la norteamericana Alexis Blokhina por 6\/2 y 6\/0 y jugar\u00e1 en la otra semifinal ante Irene Burillo, que elimin\u00f3 a la m\u00e1xima favorita, la suiza Leonie Kung (230 WTA), tras ganarle por 6\/2 y 6\/0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chilecite\u00f1a venci\u00f3 a la turca Ipek Oz por 7\/5 y 6\/2 y avanz\u00f3 en el W35 de Bastad, donde&hellip;<\/p>\n","protected":false},"author":2,"featured_media":9065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9599"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/9599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/9065"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}