{"id":13572,"date":"2025-10-30T01:50:46","date_gmt":"2025-10-30T01:50:46","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=13572"},"modified":"2025-10-30T15:36:55","modified_gmt":"2025-10-30T15:36:55","slug":"boxeo-marcelo-calivar-viajo-a-buenos-aires-al-cenard","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/10\/30\/boxeo-marcelo-calivar-viajo-a-buenos-aires-al-cenard\/","title":{"rendered":"BOXEO: MARCELO CALIVAR VIAJ\u00d3 A BUENOS AIRES AL CENARD"},"content":{"rendered":"<p style=\"text-align: justify;\">El p\u00fagil nacido en Vichigasta est\u00e1 en la convocatoria nacional.<!--more--><\/p>\n<p style=\"text-align: justify;\">El chilecite\u00f1o, radicado en San Fernando del Valle de Catamarca, Marcelo Ram\u00f3n Calivar y el catamarque\u00f1o Felipe Fernando Adauto, viajaron este martes, para cumplir con la convocatoria del Lic. Daniel Gonz\u00e1lez, Jefe de Equipo de la Selecci\u00f3n Argentina, para realizar una concentraci\u00f3n en el Centro Nacional de Alto Rendimiento Deportivo (CENARD), en Buenos Aires.<br \/>\nMarcelo Calivar (64 Kg) no pudo viajar a la localidad de Puerto Deseado, provincia de Santa Cruz, para participar del nacional masculino de mayores (iba a representar a Catamarca), por no haber podido reunir los recursos econ\u00f3micos para pagar sus gastos de traslado.<br \/>\nCalivar, de 23 a\u00f1os, hab\u00eda conseguido la clasificaci\u00f3n al Nacional al vencer en la final del Regional del NOA, por abandono, en el tercer round, a Joaqu\u00edn Allegrini (Tucum\u00e1n), en el Centro Deportivo Municipal N\u00b0 1 del Parque San Mart\u00edn, San Salvador de Jujuy, en el mes de septiembre.<br \/>\nAdauto, de 20 a\u00f1os, hab\u00eda perdido por puntos la final (60 Kg), del Regional del NOA, frente al tucumano Santiago D\u00e9cima, por lo que no clasific\u00f3 para el reciente Nacional que tuvo como sede a la localidad de Puerto Deseado, provincia de Santa Cruz.<br \/>\nTanto Calivar como Adauto, pertenecen al &#8220;New Boxing&#8221;, de la ciudad de San Fernando del Valle de Catamarca, liderado por el entrenador Rodrigo Ag\u00fcero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El p\u00fagil nacido en Vichigasta est\u00e1 en la convocatoria nacional.<\/p>\n","protected":false},"author":2,"featured_media":13573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=13572"}],"version-history":[{"count":1,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13572\/revisions"}],"predecessor-version":[{"id":13574,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13572\/revisions\/13574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/13573"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=13572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=13572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=13572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}