{"id":13461,"date":"2025-10-24T12:26:49","date_gmt":"2025-10-24T12:26:49","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=13461"},"modified":"2025-10-26T14:23:08","modified_gmt":"2025-10-26T14:23:08","slug":"jazz-ortenzi-va-por-la-consagracion-en-colombia","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/10\/24\/jazz-ortenzi-va-por-la-consagracion-en-colombia\/","title":{"rendered":"JAZZ ORTENZI VA POR LA CONSAGRACI\u00d3N EN COLOMBIA"},"content":{"rendered":"<p style=\"text-align: justify;\">La riojana venci\u00f3 por 6 \/1 y 6\/3 a la chilena Antonia Vergara y este s\u00e1bado disputar\u00e1 la final del Torneo W50 de Ibagu\u00e9.<!--more--><br \/>\nJazm\u00edn Ortenzi dio un paso decisivo en Colombia, ya que este viernes logr\u00f3 meterse en la final del Torneo W50 de Ibagu\u00e9, que reparte 40 mil d\u00f3lares en premios y puntos para el ranking WTA y que se disputa en el &#8220;Parque de Raquetas&#8221; de Tolima.<br \/>\nEn una de las semifinales que se disput\u00f3 este viernes, Ortenzi (segunda favorita al t\u00edtulo) ratific\u00f3 el gran rendimiento que viene mostrando a lo largo de toda la semana y venci\u00f3 sin atenuantes a la chilena Antonia Vergara, a quien derrot\u00f3 en sets consecutivos por 6\/1 y 6\/3.<br \/>\nLa victoria se consum\u00f3 en 1 hora y 26 minutos de juego, en los cuales la chilecite\u00f1a impuso las condiciones y domin\u00f3 con solidez en todos los aspectos del juego, dejando sin chances a la rival, que nunca pudo discutirle el control de las acciones.<br \/>\nDe esta manera, la riojana se impuso en su segundo enfrentamiento ante la chilena, a quien ya le hab\u00eda ganado en marzo con la selecci\u00f3n argentina, en el marco del grupo Americano de la Billie Jean King Cup.<br \/>\nEste s\u00e1bado jugar\u00e1 la final del Torneo, donde buscar\u00e1 su primer t\u00edtulo en un torneo de esta jerarqu\u00eda, recordando que gan\u00f3 diez W15 y un W35. Su rival en el partido decisivo ser\u00e1 la griega Despina Papamichail, que en la otra semifinal derrot\u00f3 sin problemas a la argentina Carla Markus, a quien venci\u00f3 por un doble 6\/2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La riojana venci\u00f3 por 6 \/1 y 6\/3 a la chilena Antonia Vergara y este s\u00e1bado disputar\u00e1 la final del&hellip;<\/p>\n","protected":false},"author":2,"featured_media":12802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-13461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=13461"}],"version-history":[{"count":1,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13461\/revisions"}],"predecessor-version":[{"id":13462,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13461\/revisions\/13462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/12802"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=13461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=13461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=13461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}