{"id":13225,"date":"2025-10-14T17:05:55","date_gmt":"2025-10-14T17:05:55","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=13225"},"modified":"2025-10-14T17:05:55","modified_gmt":"2025-10-14T17:05:55","slug":"ciclismo-agustina-vega-fue-sub-campeona-nacional-en-la-pista-de-chilecito","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/10\/14\/ciclismo-agustina-vega-fue-sub-campeona-nacional-en-la-pista-de-chilecito\/","title":{"rendered":"CICLISMO: AGUSTINA VEGA FUE SUB.CAMPEONA NACIONAL EN LA PISTA DE CHILECITO"},"content":{"rendered":"<p style=\"text-align: justify;\">M\u00e1s de 140 pedalistas de todo el pa\u00eds fueron parte de quinta y \u00faltima fecha el pasado domingo.<!--more--><\/p>\n<p style=\"text-align: justify;\">Chilecito fue escenario este domingo de la quinta y \u00faltima fecha de la temporada del Campeonato Nacional Infanto\/Juvenil. La pedalista local Agustina Vega fue cuarta en damas menores, y por los puntos del anual qued\u00f3 segunda.<br \/>\nEn otras categor\u00edas Oscar Perea fue tercero en categor\u00eda 4-5 a\u00f1os, Marcos Rosales (6\u00b0) y Car\u00edn Vargas (9\u00b0) en categor\u00eda 2018, y Francisco Vargas fue noveno en la categor\u00eda 2016.<\/p>\n<p style=\"text-align: justify;\">La dirigencia del Club Ciclista Perla del Oeste dijo; \u201cpas\u00f3 la \u00faltima fecha del Campeonato Nacional Infanto\/Juvenil Chilecito 2025 contamos con la participaci\u00f3n de 143 ciclistas, queremos agradecer a todos los padres y ciclistas que se llegaron de distintas provincias del pa\u00eds y del pa\u00eds vecino de Uruguay, para participar de esta fecha\u201d.<br \/>\n\u201cAgradecer a toda la gente que nos acompa\u00f1aron para que esto salga de la mejor manera a los integrantes del club quienes hicieron un trabajo arduo, a la Asociaci\u00f3n de Ciclismo del Oeste Riojano A.C.O.R, al se\u00f1or Intendente Rodrigo Brizuela y Doria, al secretario de deporte Jorge Castro\u201d.<br \/>\n\u201cTambi\u00e9n a los que nos acompa\u00f1aron dando lo mejor de ellos trabajando para que todo quede y salga de la mejor manera: Vega Isidro, Arias Rosa, Agustina Vega, Edith Arias, Mario Sotomayor, Vega Lorena, Viera Alberto, Santiago Vega, Araujo Mario, Federico Vega, Viera Regina, Oscar Ju\u00e1rez, Portugal Cesar, Arias Norma, Pablo Vega.<br \/>\nMiguel Uriche, adem\u00e1s al servicio de ambulancia AMEN, y su personal\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 140 pedalistas de todo el pa\u00eds fueron parte de quinta y \u00faltima fecha el pasado domingo.<\/p>\n","protected":false},"author":2,"featured_media":13226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=13225"}],"version-history":[{"count":1,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13225\/revisions"}],"predecessor-version":[{"id":13227,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13225\/revisions\/13227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/13226"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=13225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=13225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=13225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}