{"id":13199,"date":"2025-10-16T00:05:17","date_gmt":"2025-10-16T00:05:17","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=13199"},"modified":"2025-10-18T12:33:32","modified_gmt":"2025-10-18T12:33:32","slug":"los-andes-local-de-defensores-el-sabado-por-el-federal-amateurs","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/10\/16\/los-andes-local-de-defensores-el-sabado-por-el-federal-amateurs\/","title":{"rendered":"ESTRENO, LOS ANDES LOCAL DE DEFENSORES, EL S\u00c1BADO POR EL FEDERAL AMATEURS 2025\/26"},"content":{"rendered":"<p style=\"text-align: justify;\">Ser\u00e1 la primera fecha de la zona 17 de la Regi\u00f3n Centro. El juego va en El Parque (local Los Andes) desde las 18 horas.<!--more--><\/p>\n<p style=\"text-align: justify;\">Comienza el fin de semana que viene el Federal para los equipos de la Liga Chilecite\u00f1a, habr{a duelo entre Los Andes \u2013 Defensores, mismos rivales en la finales de zona del campeonato local (fue 0 a 0 en la ida).<\/p>\n<p style=\"text-align: justify;\">Los clubes acordaron jugar este s\u00e1bado por la tarde en el Parque, local el Sarmientino del Xeneize por esta primera fecha.<\/p>\n<p style=\"text-align: justify;\">Por su parte en la zona 15, el elenco nonogaste\u00f1o de J.V.Gonz\u00e1lez tendr\u00e1 fecha libre este fin de semana.<\/p>\n<p><strong>REVANCHA FINAL<\/strong><\/p>\n<p style=\"text-align: justify;\">Por su parte, Los Andes y Defensores tambi\u00e9n son finalistas de la fase de las zonas, el s\u00e1bado pasada igualaron en cero, y con esto del Federal, la fecha de la revancha final no est\u00e1 determinada, pero podr\u00eda ser en entresemana de esta u la otra semana por la noche.<\/p>\n<p style=\"text-align: justify;\">Es local Los Andes, y ese juego\u00a0 ir\u00eda por la noche en cancha de Atl\u00e9tico Chilecito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 la primera fecha de la zona 17 de la Regi\u00f3n Centro. El juego va en El Parque (local Los&hellip;<\/p>\n","protected":false},"author":2,"featured_media":13200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=13199"}],"version-history":[{"count":3,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13199\/revisions"}],"predecessor-version":[{"id":13272,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/13199\/revisions\/13272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/13200"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=13199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=13199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=13199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}