{"id":11755,"date":"2025-08-18T00:16:28","date_gmt":"2025-08-18T00:16:28","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=11755"},"modified":"2025-08-18T00:16:28","modified_gmt":"2025-08-18T00:16:28","slug":"futbol-liga-12o-fecha-en-el-final-el-rojiengro-sanogasteno-se-impuso-a-joaquin","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/08\/18\/futbol-liga-12o-fecha-en-el-final-el-rojiengro-sanogasteno-se-impuso-a-joaquin\/","title":{"rendered":"F\u00daTBOL LIGA \u2013 12\u00ba FECHA: EN EL FINAL, EL ROJIENGRO SA\u00d1OGASTE\u00d1O SE IMPUSO A JOAQU\u00cdN"},"content":{"rendered":"<p style=\"text-align: justify;\">Fue 2 a 1 para Newell\u00b4s ante los nonogaste\u00f1os de Joaqu\u00edn V. Gonz\u00e1lez. Hubo cuatro jugadores expulsados.<!--more--><\/p>\n<p style=\"text-align: justify;\">Jugando en casa, Newell\u00b4s de Sa\u00f1ogasta cosech\u00f3 la segunda victoria consecutiva, y esta vez fue ante un rival cl\u00e1sico de los distritos del sud.oeste del departamento.<br \/>\nEn el minuto final de la etapa principal el local se pone arriba en el tanteador por intermedio de Nico Mor\u00e1n, para establecer el uno a cero parcial.<br \/>\nEn un juego de varias expulsiones, en Joaqu\u00edn se fueron Enzo Mac\u00edas, Andr\u00e9s Mu\u00f1oz y Santiago Baz\u00e1n, y en el Rojinegro roja para Jonatan Cayo.<br \/>\nY sobre los minutos finales del partdido, fue de pura emociones, ya que a los 45 lo empata Joaqu\u00edn por interemedio de Nicol\u00e1s Mor\u00e1n; pero la respuesta fue inmediata de los sa\u00f1ogaste\u00f1os que de nuevo por intermedio de Nico \u201cMaquinita\u201d Mor\u00e1n, para el triunfo ag\u00f3nico por dos a uno para los dirigidos por Fabi\u00e1n Rementeria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue 2 a 1 para Newell\u00b4s ante los nonogaste\u00f1os de Joaqu\u00edn V. Gonz\u00e1lez. Hubo cuatro jugadores expulsados.<\/p>\n","protected":false},"author":2,"featured_media":11756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-11755","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11755"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11755\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11756"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}