{"id":11746,"date":"2025-08-21T00:03:03","date_gmt":"2025-08-21T00:03:03","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=11746"},"modified":"2025-08-23T16:13:45","modified_gmt":"2025-08-23T16:13:45","slug":"bebe-pozo-gano-por-ko-y-antes-de-fin-de-ano-debutara-como-profesional","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/08\/21\/bebe-pozo-gano-por-ko-y-antes-de-fin-de-ano-debutara-como-profesional\/","title":{"rendered":"\u201cBEB\u00c9\u201d POZO GAN\u00d3 POR KO Y ANTES DE F\u00cdN DE A\u00d1O DEBUTAR\u00c1 COMO PROFESIONAL"},"content":{"rendered":"<p style=\"text-align: justify;\">Nueva victoria para el p\u00fagil chilecite\u00f1o en territorio de C\u00f3rdoba.<!--more--><\/p>\n<p style=\"text-align: justify;\">El chilecite\u00f1o, radicado en C\u00f3rdoba, Javier Ever Pozo (69 Kg) venci\u00f3 por KO1 al cordob\u00e9s Mariano Clavero. Este combate integr\u00f3 la extensa programaci\u00f3n de la velada, que se realiz\u00f3 este s\u00e1bado 16 de agosto, en el Gimnasio de la Asociaci\u00f3n Civil de T\u00e9cnicos de Boxeo de C\u00f3rdoba (A.C.T.B.C.), ciudad de C\u00f3rdoba.<br \/>\nEl entrenador cordob\u00e9s Diego S\u00edvori, titular del gimnasio &#8220;El Aguante&#8221;, que funciona en la ciudad de C\u00f3rdoba, asegur\u00f3 a los programas radiales &#8220;SEGUNDOS AFUERA&#8221; y &#8220;A PU\u00d1O LIMPIO&#8221;, que Pozo, de 25 a\u00f1os, debutar\u00e1 como profesional antes de fin de a\u00f1o.<\/p>\n<p style=\"text-align: justify;\">REDACCI\u00d3N: Daniel Gutierrez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva victoria para el p\u00fagil chilecite\u00f1o en territorio de C\u00f3rdoba.<\/p>\n","protected":false},"author":2,"featured_media":11747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11746"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11747"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}