{"id":11634,"date":"2025-08-13T09:24:10","date_gmt":"2025-08-13T09:24:10","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=11634"},"modified":"2025-08-14T04:39:46","modified_gmt":"2025-08-14T04:39:46","slug":"vuelve-la-accion-de-la-copa-libertadores-y-sudamericana-con-los-octavos-de-final","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/08\/13\/vuelve-la-accion-de-la-copa-libertadores-y-sudamericana-con-los-octavos-de-final\/","title":{"rendered":"JUEVES DE &#8220;ACCI\u00d3N&#8221; EN LA COPA LIBERTADORES Y SUDAMERICANA, CON LOS OCTAVOS DE FINAL"},"content":{"rendered":"<p style=\"text-align: justify;\">La fase eliminatoria de los dos principales torneos de clubes del f\u00fatbol sudamericano se comenzar\u00e1n este martes con las primeras llaves de octavos de final.<!--more--><\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s de un largo receso, la Copa Libertadores y la Copa Sudamericana dar\u00e1n inicio esta semana a la fase de eliminaci\u00f3n directa camino a la consagraci\u00f3n. Nueve equipos argentinos, en total, ser\u00e1n parte de la competencia en los dos torneos.<br \/>\nLa final de la Copa Libertadores se jugar\u00e1 el 29 de noviembre en el estadio Nacional de Lima (Per\u00fa) y la definici\u00f3n de la Sudamericana ser\u00e1 una semana antes en Santa Cruz de la Sierra, Bolivia.<\/p>\n<p style=\"text-align: justify;\"><strong>COPA LIBERTADORES<\/strong><br \/>\nOCTAVOS DE FINAL \u2013 IDA<\/p>\n<p style=\"text-align: justify;\"><em>* Martes 12\/08<\/em><br \/>\n-En Fortaleza (19:00): Fortaleza (Brasil) &#8211; <strong>V\u00e9lez Sarsfield<\/strong><br \/>\n-En Medell\u00edn (21:30): Atl\u00e9tico Nacional (Colombia) &#8211; San Pablo Paulo (Brasil)<br \/>\n-En Montevideo (21:30): Pe\u00f1arol (Uruguay) &#8211; <strong>Racing Club<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>*Mi\u00e9rcoles 13\/08<\/em><br \/>\n-En Asunci\u00f3n (19:00): Cerro Porte\u00f1o (Paraguay) &#8211; <strong>Estudiantes de La Plata<\/strong><br \/>\n-En Rio de Janeiro (21:30): Flamengo (Brasil) &#8211; Internacional (Brasil)<\/p>\n<p style=\"text-align: justify;\"><em>*Jueves 14\/08<\/em><br \/>\n-En Rio de Janeiro (19:00): Botafogo (Brasil) &#8211; Liga de Quito (Ecuador)<br \/>\n-En Lima (21:30): Universitario (Per\u00fa) &#8211; Palmeiras (Brasil)<br \/>\n-En Asunci\u00f3n (21:30): Libertad (Paraguay) &#8211; <strong>River Plate<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>COPA SUDAMERICANA<\/strong><br \/>\nOCTAVOS DE FINAL DE IDA<\/p>\n<p style=\"text-align: justify;\"><em>*Martes 12\/08<\/em><br \/>\n-En Manizales (19:00): Once Caldas (Colombia) \u2013 <strong>Hurac\u00e1n<\/strong><br \/>\n-En Quito (21:30): Independiente del Valle (Ecuador) &#8211; Mushuc Runa (Ecuador)<br \/>\n-En Cali (21:30): Am\u00e9rica de Cali (Colombia) &#8211; Fluminense (Brasil)<\/p>\n<p style=\"text-align: justify;\"><em>*Mi\u00e9rcoles 13\/08<\/em><br \/>\n-En La Paz (19:00): Bol\u00edvar (Bolivia) &#8211; Cienciano (Per\u00fa)<br \/>\n-En Lima (21:30): Alianza Lima (Per\u00fa) &#8211; Universidad Cat\u00f3lica (Ecuador)<br \/>\n-En Santiago (21:30): Universidad de Chile (Chile) \u2013 <strong>Independiente<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>*Jueves 14\/08<\/em><br \/>\n-En Belo Horizonte (19:00): Atl\u00e9tico Mineiro (Brasil) &#8211; <strong>Godoy Cruz (Mendoza)<\/strong><br \/>\n-En Santiago del Estero (21:30): <strong>Central C\u00f3rdoba (Santiago del Estero)<\/strong> &#8211; <strong>Lan\u00fas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fase eliminatoria de los dos principales torneos de clubes del f\u00fatbol sudamericano se comenzar\u00e1n este martes con las primeras&hellip;<\/p>\n","protected":false},"author":2,"featured_media":11635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-11634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11634"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11635"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}