{"id":11619,"date":"2025-08-11T02:21:28","date_gmt":"2025-08-11T02:21:28","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=11619"},"modified":"2025-08-11T02:21:28","modified_gmt":"2025-08-11T02:21:28","slug":"futbol-liga-11o-fecha-anguinan-se-tomo-revancha-de-union-en-el-clasico-parcelero","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/08\/11\/futbol-liga-11o-fecha-anguinan-se-tomo-revancha-de-union-en-el-clasico-parcelero\/","title":{"rendered":"F\u00daTBOL LIGA \u2013 11\u00ba FECHA: ANGUIN\u00c1N SE TOM\u00d3 \u201cREVANCHA\u201d DE UNI\u00d3N EN EL CL\u00c1SICO PARCELERO"},"content":{"rendered":"<p style=\"text-align: justify;\">\nLo perd\u00eda por dos goles, y el Verdolaga lo dio vuelta para ganarlo por 3 a 2 ante el Albo de Malligasta.<!--more--> A cancha llena este domingo en el Eduardo Ju\u00e1rez, hubo cl\u00e1sico parcelero en la revancha, que tuvo emociones a radiar en la primera etapa, donde el Verdolaga se tom\u00f3 revancha de Uni\u00f3n de lo sucedido hace unos semanas en la ida de este duelo, y sigue en el tercer lugar de la zona A.<br \/>\nA todo ritmo el inicio del juego, con un Uni\u00f3n certero, aprovechando los errores del rival, a los 8 minutos gol de Alfredo As\u00eds para el uno a cero, en tanto que a los 15\u00b4 el segundo fue de Amin P\u00e1ez.<br \/>\nSe \u201cdespert\u00f3\u201d el Verde, a los 27 descuenta Jony Gonz\u00e1lez , luego a los 35 minutos tanto de buena factura de Marcelo Portugal (h) para empatar el juego. Sin dudas que un cl\u00e1sico a puras emociones, y a los 44 minutos, el local lo da vuelta, por la conquista de Fernando Cerda para el tres a dos.<br \/>\nEn el segundo tiempo, fue de lucha como cl\u00e1sico, el Verde aferr\u00e1ndose al triunfo, que lleg\u00f3 y que fue muy festejado por sus parciales, tom\u00e1ndose revancha de la sucedido en ida en territorio de Malligasta, cuando en aquella ocasi\u00f3n ganaron los de la U por tres a cero.<br \/>\nAhora, los dirigidos por Edgard D\u00edaz siguen terceros, pero mas cerca del segundo Joaqu\u00edn, pues los separa un solo punto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo perd\u00eda por dos goles, y el Verdolaga lo dio vuelta para ganarlo por 3 a 2 ante el Albo&hellip;<\/p>\n","protected":false},"author":2,"featured_media":11620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-11619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11619"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11620"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}