{"id":11556,"date":"2025-08-08T00:45:16","date_gmt":"2025-08-08T00:45:16","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=11556"},"modified":"2025-08-08T13:45:44","modified_gmt":"2025-08-08T13:45:44","slug":"garnacho-deja-el-manchester-united-y-se-va-al-chelsea","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/08\/08\/garnacho-deja-el-manchester-united-y-se-va-al-chelsea\/","title":{"rendered":"GARNACHO DEJA EL MANCHESTER UNITED, Y SE VA AL CHELSEA"},"content":{"rendered":"<p style=\"text-align: justify;\">El jugador de la Selecci\u00f3n Argentina ya cerr\u00f3 de palabra su v\u00ednculo con el \u00faltimo campe\u00f3n del Mundial de Clubes, donde compartir\u00e1 plantel con Enzo Fern\u00e1ndez y Aar\u00f3n Anselmino, y solo falta que se pongan de acuerdo con el Manchester.<!--more--><\/p>\n<p style=\"text-align: justify;\">Alejandro Garnacho est\u00e1 muy cerca de dejar el Manchester United y sumarse al Chelsea, donde est\u00e1n los argentinos\u00a0Enzo Fern\u00e1ndez, su compa\u00f1ero en la Selecci\u00f3n, y el ex-Boca\u00a0Aar\u00f3n Anselmino. El extremo hispano-argentino ya\u00a0tiene cerrado su contrato con el \u00faltimo campe\u00f3n del Mundial de Clubes y s\u00f3lo falta el acuerdo entre las instituciones.<\/p>\n<p style=\"text-align: justify;\">Desde el final de la temporada pasada se sab\u00eda que el futbolista de 21 a\u00f1os iba a abandonar los Red Devils debido a su\u00a0mala relaci\u00f3n con el entrenador R\u00faben Amorim. El entrenador portugu\u00e9s lo releg\u00f3 al banco de suplentes en buena parte de la temporada y el v\u00ednculo lleg\u00f3 a un punto de no retorno tras la final de la Europa League.\u00a0&#8220;Obviamente es duro para todos, despu\u00e9s de esta temporada que, la verdad, fue una mierda.\u00a0Hasta la final, he jugado todas las rondas, he ayudado al equipo. Hoy, jugar 20 minutos&#8230; no s\u00e9&#8221;,\u00a0hab\u00eda dicho Garnacho. A lo que el DT respondi\u00f3:\u00a0&#8220;Es f\u00e1cil decirlo ahora. \u00bfQui\u00e9n fall\u00f3 una clara oportunidad en el primer tiempo de las semifinales? Garnacho. El f\u00fatbol es as\u00ed&#8221;.<\/p>\n<p style=\"text-align: justify;\">Para colmo, el m\u00e1ximo ganador de la Premier League\u00a0<a href=\"https:\/\/www.tycsports.com\/futbol-internacional\/cambios-en-manchester-united-nueva-delantera-de-mas-de-200-millones-de-euros-y-el-precio-de-garnacho-id678575.html\">conform\u00f3 una delantera de m\u00e1s de 200 millones de euros<\/a>\u00a0en este mercado de pases. Contrat\u00f3 a\u00a0Bryan Mbeumo\u00a0del Brentford por 81 millones de euros, a\u00a0Matheus Cunha\u00a0de Wolverhampton a cambio de 73 y esta semana cerr\u00f3 a\u00a0Benjamin \u0160e\u0161ko\u00a0de RB Leipzig por 76,5 millones m\u00e1s otros 8,5 en variables.<\/p>\n<p style=\"text-align: justify;\">Garnacho era consciente de que se ten\u00eda que buscar una salida en este mercado y\u00a0su deseo de continuar en la Premier lo hizo rechazar ofertas del Napoli, del futbol espa\u00f1ol y\u00a0<a href=\"https:\/\/www.tycsports.com\/premier-league\/garnacho-rechazo-jugar-con-cristiano-ronaldo-en-al-nassr-id673780.html\">una millonaria del Al-Nassr de Arabia Saudita<\/a>, donde iba a tener la oportunidad de volver a coincidir con su \u00eddolo, Cristiano Ronaldo.<\/p>\n<p style=\"text-align: justify;\">La negociaci\u00f3n con el Chelsea data de hace varias semanas, pero los compromisos del conjunto londinense en el Mundial de Clubes la enfriaron. Ahora que el United renov\u00f3 su delantera y que<a href=\"https:\/\/www.tycsports.com\/premier-league\/noni-madueke-abandono-chelsea-antes-de-la-final-con-psg-firmo-con-arsenal-y-ya-es-criticado-id674564.html\">\u00a0los Blues vendieron a Noni Madueke al Arsenal a cambio de 48 millones de libras<\/a>, volvieron a acelerar para hacerse con los servicios del futbolista de la Selecci\u00f3n Argentina.<\/p>\n<p style=\"text-align: justify;\">El acuerdo contractual est\u00e1 y s\u00f3lo falta que haya un cierre entre los clubes en los montos de la transferencia. Desde Inglaterra informan que\u00a0el Manchester no lo dejar\u00e1 ir por menos de 80 millones de euros\u00a0debido a su potencial y a que deben recuperar la gran inversi\u00f3n que hicieron en este mercado. Todo parece encaminado para que el Garnacho se mude a la capital inglesa.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>*Los n\u00fameros de Alejandro Garnacho en Manchester United<\/strong><\/p>\n<p style=\"text-align: justify;\">El argentino peg\u00f3 el salto a la primera de los Red Devils en 2022. Desde entonces,\u00a0disput\u00f3 144 partidos, marc\u00f3 26 goles y reparti\u00f3 22 asistencias. Adem\u00e1s, obtuvo la Copa de la Liga en 2023 y la FA Cup en 2024 tras derrotar por 2-1 a Manchester City en la final.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jugador de la Selecci\u00f3n Argentina ya cerr\u00f3 de palabra su v\u00ednculo con el \u00faltimo campe\u00f3n del Mundial de Clubes,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":11557,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-11556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11556"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11557"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}