{"id":11293,"date":"2025-07-26T11:48:42","date_gmt":"2025-07-26T11:48:42","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=11293"},"modified":"2025-07-28T02:09:23","modified_gmt":"2025-07-28T02:09:23","slug":"futbol-del-domingo-los-andes-busca-estirar-la-diferencia-en-la-zona-b","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/07\/26\/futbol-del-domingo-los-andes-busca-estirar-la-diferencia-en-la-zona-b\/","title":{"rendered":"F\u00daTBOL DEL DOMINGO: LOS ANDES BUSCA ESTIRAR LA DIFERENCIA EN LA ZONA \u201cB\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\">El Sarmientino visita a Los Chuyos. Adem\u00e1s este domingo, Estrella \u2013 Independiente, y Anguin\u00e1n \u2013 Newell\u00b4s.<!--more--><\/p>\n<p style=\"text-align: justify;\">Los restantes tres juegos de la fecha 9 de la Liga Chilecite\u00f1a de F\u00fatbol se van a jugar este domingo por la tarde ; Los Chuyos es local de Los Andes desde las 16.15 horas en el estadio del Tricolor, en el estadio \u201cEduardo Ju\u00e1rez\u201d el Club Anguin\u00e1n va ante Newell\u00b4s Old Boys, a las 16.15 horas; por su parte Estrella Roja confronta con Independiente en la cancha del Rojo, desde las 16.15 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Sarmientino visita a Los Chuyos. Adem\u00e1s este domingo, Estrella \u2013 Independiente, y Anguin\u00e1n \u2013 Newell\u00b4s.<\/p>\n","protected":false},"author":2,"featured_media":11294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-11293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11293"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11294"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}