{"id":11136,"date":"2025-07-21T00:29:44","date_gmt":"2025-07-21T00:29:44","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=11136"},"modified":"2025-07-21T17:54:54","modified_gmt":"2025-07-21T17:54:54","slug":"final-infartante-boca-es-bicampeon-de-la-liga-nacional-de-basquet","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/07\/21\/final-infartante-boca-es-bicampeon-de-la-liga-nacional-de-basquet\/","title":{"rendered":"BOCA, ES &#8220;BICAMPE\u00d3N&#8221; DE LA LIGA NACIONAL DE B\u00c1SQUET, EN UN FINAL INFARTANTE"},"content":{"rendered":"<p style=\"text-align: justify;\">En el s\u00e9ptimo juego final, el Xeneize se impuso a Instituto por 78 a 77.<\/p>\n<p style=\"text-align: justify;\">A tono con lo que fueron todos los partidos de estas apasionantes Finales, el Xeneize le gan\u00f3 a Instituto el Juego 7 por UN PUNTO y dio la vuelta en La Bombonerita. TRIPLE DECISIVO de Scala, con 9.4 segundos en el reloj<\/p>\n<p style=\"text-align: justify;\">As\u00ed qued\u00f3 la lista de campeones: Atenas de C\u00f3rdoba: 9, Pe\u00f1arol de Mar del Plata: 5, San Lorenzo: 5, y Boca: 5.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el s\u00e9ptimo juego final, el Xeneize se impuso a Instituto por 78 a 77. A tono con lo que&hellip;<\/p>\n","protected":false},"author":2,"featured_media":11137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=11136"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/11136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/11137"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=11136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=11136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=11136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}