{"id":10944,"date":"2025-07-11T01:30:39","date_gmt":"2025-07-11T01:30:39","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=10944"},"modified":"2025-07-13T01:08:04","modified_gmt":"2025-07-13T01:08:04","slug":"liga-chilecitena-futbol-del-sabado-en-el-parque-y-anguinan","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/07\/11\/liga-chilecitena-futbol-del-sabado-en-el-parque-y-anguinan\/","title":{"rendered":"LIGA CHILECITE\u00d1A: F\u00daTBOL DEL S\u00c1BADO EN EL PARQUE Y ANGUIN\u00c1N"},"content":{"rendered":"<p style=\"text-align: justify;\">Vuelve el f\u00fatbol de la Liga Chilecite\u00f1a, este s\u00e1bado el Xeneize es local de Uni\u00f3n, y Anguin\u00e1n recibe a Newell\u00b4s de Sa\u00f1ogasta.<!--more--><\/p>\n<p style=\"text-align: justify;\">Luego de dos semanas de inactividad, vuelve el f\u00fatbol chilecite\u00f1o con la s\u00e9ptima fecha del campeonato 2025 a jugarse este s\u00e1bado 12 y domingo 13 de julio en primera divisi\u00f3n, y en todas las divisiones.<\/p>\n<p style=\"text-align: justify;\">Este s\u00e1bado, en El Parque, Defensores de la Plata el puntero de la zona A recibe a Uni\u00f3n de Malligasta a partir de las 16.15 horas, en la localidad de Anguin\u00e1n, el Verde ser\u00e1 anfitri\u00f3n de NOB de Sa\u00f1ogasta, juego tambi\u00e9n a iniciarse a las 16.15 horas.<br \/>\nCompletan el domingo, en la localidad de Nonogasta, el due\u00f1o de casa J.V.Gonz\u00e1lez ir\u00e1 ante Los Andes (puntero de la zona B); por su parte en la ciudad, Atl\u00e9tico Chilecito recibe a Newell\u00b4s de Chilecito en la cancha del Celeste; en tanto que Estrella Roja juega con San Buenaventura en cancha de Independiente, y Los Chuyos va ante Independiente, en el predio del Tricolor en los 80 lotes.<\/p>\n<p><strong>LA PROGRAMACI\u00d3N de la 7\u00b0 fecha<\/strong><br \/>\n<em><strong>*S\u00e1bado 12 de julio<\/strong><\/em><br \/>\nCancha: Defensores de la Plata<br \/>\n-16.15 hs. Defensores vs. Uni\u00f3n<br \/>\nCancha: Anguin\u00e1n<br \/>\n-16.15 hs. Anguin\u00e1n vs. NOB de Sa\u00f1ogasta<\/p>\n<p><em><strong>*Domingo 13 de julio<\/strong><\/em><br \/>\nCancha: Joaqu\u00edn (Nonogasta)<br \/>\n-16.15 hs. J.V.Gonz\u00e1lez vs. Los Andes<br \/>\nCancha: Atl\u00e9tico Chilecito<br \/>\n-16.15 hs. Atl\u00e9tico Chilecito vs. Newell\u00b4s<br \/>\nCancha: Independiente<br \/>\n-16.15 hs. Estrella Roja vs. San Buenaventura<br \/>\nCancha: Los Chuyos<br \/>\n-16.15 hs. Los Chuyos vs. Independiente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vuelve el f\u00fatbol de la Liga Chilecite\u00f1a, este s\u00e1bado el Xeneize es local de Uni\u00f3n, y Anguin\u00e1n recibe a Newell\u00b4s&hellip;<\/p>\n","protected":false},"author":2,"featured_media":10945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10944"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10944\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10945"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}