{"id":10745,"date":"2025-07-04T02:10:57","date_gmt":"2025-07-04T02:10:57","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=10745"},"modified":"2025-07-06T00:59:55","modified_gmt":"2025-07-06T00:59:55","slug":"sigue-suspendido-el-futbol-de-la-liga-chilecitena-por-la-cuestion-sanitaria-y-de-salud-de-los-jugadores","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/07\/04\/sigue-suspendido-el-futbol-de-la-liga-chilecitena-por-la-cuestion-sanitaria-y-de-salud-de-los-jugadores\/","title":{"rendered":"LIGA CHILECITE\u00d1A: SIGUE SUSPENDIDO EL F\u00daTBOL, POR LA SITUACI\u00d3N SANITARIA"},"content":{"rendered":"<p style=\"text-align: justify;\">Segunda semana consecutiva sin f\u00fatbol en Chilecito. <!--more--><\/p>\n<p style=\"text-align: justify;\">Por unanimidad los clubes de la Liga Chilecite\u00f1a acordaron este mi\u00e9rcoles por la noche, continuar con la suspensi\u00f3n del campeonato 2025 en todas las divisiones, hasta que mejore la situaci\u00f3n sanitaria y de salud en todo el departamento, y que aqueja en estos tiempos a toda la provincia de La Rioja, y\u00a0 gran parte del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Acatando las medias de prevensi\u00f3n que viene impulsado el gobierno provincial de resguardar la salud, as\u00ed lo ha expresado Walter Arga\u00f1araz, el presidente de la Liga Chilecite\u00f1a de F\u00fatbol, &#8220;esto ser\u00e1 de semana a semana, de ir analizando la situaci\u00f3n del fr\u00edo que genera inconvenientes en la salud de la poblaci\u00f3n en general, y en este caso a muchos de los jugadores del f\u00fatbol chilecite\u00f1o, en especial de las divisiones inferiores&#8221;.<\/p>\n<p style=\"text-align: justify;\">Por segunda semana consecutiva sin f\u00fatbol en Chilecito, desde la dirigencia de la Liga Chilecite\u00f1a, expresaron que se van a reunir el pr\u00f3ximo \u00a0mi\u00e9rcoles 9 de julio para evaluar los pasos a seguir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segunda semana consecutiva sin f\u00fatbol en Chilecito.<\/p>\n","protected":false},"author":2,"featured_media":10748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10745"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10748"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}