{"id":10433,"date":"2025-06-18T03:19:28","date_gmt":"2025-06-18T03:19:28","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=10433"},"modified":"2025-06-20T15:34:47","modified_gmt":"2025-06-20T15:34:47","slug":"jazz-ortenzi-viaja-a-gran-bretana-con-el-sueno-de-jugar-wimbledon-2025","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/06\/18\/jazz-ortenzi-viaja-a-gran-bretana-con-el-sueno-de-jugar-wimbledon-2025\/","title":{"rendered":"JAZZ ORTENZI, VIAJA A GRAN BRETA\u00d1A, CON EL \u201cSUE\u00d1O\u201d DE JUGAR WIMBLEDON 2025"},"content":{"rendered":"<p style=\"text-align: justify;\">La tenista chilecite\u00f1a viaja este jueves hacia Gran Breta\u00f1a, con la chance de disputar la qualy del Grand Slam.<!--more--><\/p>\n<p style=\"text-align: justify;\">Con la ilusi\u00f3n a cuestas, este jueves Jazm\u00edn Ortenzi viajar\u00e1 rumbo a Gran Breta\u00f1a. La tenista riojana de 23 a\u00f1os estar\u00e1 presente para firmar en el Torneo de Wimbledon, ya que tiene grandes chances de entrar en la qualy de uno de los cuatro cert\u00e1menes m\u00e1s importantes del mundo.<br \/>\nActualmente, Ortenzi, que ocupa el puesto 245\u00ba del ranking WTA, est\u00e1 a ocho lugares de ingresar a la clasificaci\u00f3n, pero cuando se otorguen las wild cards (invitaciones especiales) se liberar\u00e1n de ocho cupos, por lo que quedar\u00eda adentro de la etapa clasificatoria, que se disputar\u00e1 desde el lunes que viene, recordando que el cuadro principal del Grand Slam, comenzar\u00e1 desde el lunes 30 de junio.<\/p>\n<p style=\"text-align: justify;\">\n<strong>Las invitadas<\/strong><br \/>\nEl torneo de Wimbledon anunci\u00f3 este mi\u00e9rcoles las wild-cards femeninas. A pesar de su solicitud, Lo\u00efs Boisson no recibi\u00f3 una wild-card y, por lo tanto, tendr\u00e1 que pasar por la fase de clasificaci\u00f3n. Petra Kvitova, doble campeona de Wimbledon en 2011 y 2014, ha sido invitada por los organizadores. Los otros cupos ser\u00e1n para las brit\u00e1nicas Jodie Burrage, Harriet Dart, Francesca Jones, Hannah Klugman, Mika Stojsavljevic, Heather Watson y Mingge Xu.<br \/>\nEn caso de jugar finalmente en la qualy de Wimbledon, Ortenzi podr\u00e1 tener la chances de participar por primera vez de uno de los Grand Slams del circuito, lo cual era uno de sus principales objetivos para esta temporada, recordando que su deseo era estar presente en Roland Garros (donde adem\u00e1s tiene mayor conocimiento del tipo de superficie), pero finalmente no le dio el ranking para poder estar en el certamen parisino.<br \/>\nLuego de su participaci\u00f3n en Wimbledon, Ortnezi jugar\u00e1 otros torneos en Europa, de los cuales hasta el momento, lo \u00fanico confirmado es su presencia en el W35 de Roma, que se disputar\u00e1 desde el 30 de junio, y donde es quinta mejor preclasificada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tenista chilecite\u00f1a viaja este jueves hacia Gran Breta\u00f1a, con la chance de disputar la qualy del Grand Slam.<\/p>\n","protected":false},"author":2,"featured_media":10434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10433"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10434"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}