{"id":10412,"date":"2025-06-18T16:01:56","date_gmt":"2025-06-18T16:01:56","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=10412"},"modified":"2025-06-18T16:16:17","modified_gmt":"2025-06-18T16:16:17","slug":"futbol-chileciteno-guty-pozo-por-ahora-es-el-artillero-del-campeonato-en-cinco-fechas","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/06\/18\/futbol-chileciteno-guty-pozo-por-ahora-es-el-artillero-del-campeonato-en-cinco-fechas\/","title":{"rendered":"F\u00daTBOL CHILECITE\u00d1O: GUTY POZO, POR AHORA, ES EL \u201cARTILLERO\u201d DEL CAMPEONATO EN CINCO FECHAS"},"content":{"rendered":"<p style=\"text-align: justify;\">Los m\u00e1ximos goleadores del torneo en estas primeras fechas.<!--more--><\/p>\n<p style=\"text-align: justify;\">Algunos n\u00fameros relevantes al cabo de las primeras cinco fechas del campeonato 2025 de primera divisi\u00f3n de la Liga Chilecite\u00f1a de F\u00fatbol.<\/p>\n<p style=\"text-align: justify;\"><strong>LOS GOLEADORES<\/strong><br \/>\nGustavo Pozo (Los Chuyos) \u2013 5 goles<br \/>\nAgust\u00edn Carpio (J.V.Gonz\u00e1lez) \u2013 4<br \/>\nSantiago Maldonado (Newell\u00b4s CH) \u2013 4<br \/>\nAlexis Oliva (Independiente) \u2013 3<br \/>\nNicol\u00e1s Aguero(Defensores) \u2013 3<br \/>\nGonzalo Barrera (Estrella Roja) \u2013 3<br \/>\nLautaro S\u00e1nchez (Los Andes) \u2013 3<br \/>\nClaudio Nu\u00f1ez (San Buenaventura) \u2013 3<br \/>\nLucas Nu\u00f1ez (San Buenaventura) \u2013 3<br \/>\nDiego Olmedo (NOB de Sa\u00f1ogasta) \u2013 3<\/p>\n<p style=\"text-align: justify;\"><strong>DE LOS GOLES<\/strong><br \/>\nA lo largo de estas cinco fechas disputadas, que son un total de 30 partidos, se han anotado un total de 87 goles, un promedio de 2,9 por partido. La fecha con mas goles, fue la segunda con 22 tantos, y la fecha con menos goles, la cuarta con solo 11 goles.<br \/>\nLos locales ganaron 14 partidos, hubo 6 empates, y un total de 10 triunfos visitantes.<\/p>\n<p style=\"text-align: justify;\"><strong>FIXTURE<\/strong><br \/>\n<strong>CAMPEONATO 2025 \u2013 FASE CLASIFICACI\u00d3N<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1\u00ba FECHA<\/strong><br \/>\nJ.V.Gonz\u00e1lez (3) \u2013 Atl\u00e9tico Chilecito (2)<br \/>\nLos Chuyos (0) \u2013 Anguin\u00e1n (0)<br \/>\nIndependiente (1) \u2013 NOB de Sa\u00f1ogasta (3)<br \/>\nLos Andes (3) \u2013 Newell\u00b4s Old Boys (0)<br \/>\nSan Buenaventura (3) \u2013 Uni\u00f3n (0)<br \/>\nEstrella Roja (2) \u2013 Defensores de la Plata (1)<br \/>\n<strong>2\u00ba FECHA<\/strong><br \/>\nAtl\u00e9tico Chilecito (0) \u2013 Estrella Roja (1)<br \/>\nDefensores de la Plata (5) \u2013 Los Chuyos (1)<br \/>\nNewell\u00b4s Old Boys (2) \u2013 San Buenaventura (3)<br \/>\nAnguin\u00e1n (2) \u2013 J.V.Gonz\u00e1lez (1)<br \/>\nUni\u00f3n (3) \u2013 Independiente (1)<br \/>\nNOB de Sa\u00f1ogasta (1) \u2013 Los Andes (2)<br \/>\n<strong>3\u00ba FECHA<\/strong><br \/>\nSan Buenaventura (3) \u2013 NOB de Sa\u00f1ogasta (2)<br \/>\nUni\u00f3n (0) \u2013 Newell\u00b4s Old Boys (1)<br \/>\nIndependiente (1) \u2013 Los Andes (1)<br \/>\nDefensores de la Plata (3) \u2013 Atl\u00e9tico Chilecito (0)<br \/>\nLos Chuyos (3) \u2013 J.V.Gonz\u00e1lez (2)<br \/>\nEstrella Roja (0) \u2013 Anguin\u00e1n (1)<br \/>\n<strong>4\u00ba FECHA<\/strong><br \/>\nAnguin\u00e1n (0) \u2013 Atl\u00e9tico Chilecito (0)<br \/>\nLos Chuyos (2) \u2013 Estrella Roja (2)<br \/>\nUni\u00f3n (0) \u2013 Los Andes (1)<br \/>\nJ.V.Gonz\u00e1lez (3) \u2013 Defensores de la Plata (2)<br \/>\nIndependiente (1) \u2013 San Buenaventura (0)<br \/>\nNOB de Sa\u00f1ogasta (0) \u2013 Newell\u00b4s Old Boys (0)<br \/>\n<strong>5\u00ba FECHA<\/strong><br \/>\nEstrella Roja (1) \u2013 J.V.Gonz\u00e1lez (2)<br \/>\nAnguin\u00e1n (0) \u2013 Defensores de la Plata (1)<br \/>\nNOB de Sa\u00f1ogasta (2) \u2013 Uni\u00f3n (1)<br \/>\nAtl\u00e9tico Chilecito (1) \u2013 Los Chuyos (1)<br \/>\nNewell\u00b4s Old Boys (4) \u2013 Independiente (1)<br \/>\nSan Buenaventura (2) \u2013 Los Andes (3)<\/p>\n<p style=\"text-align: justify;\">\n6\u00ba FECHA (CL\u00c1SICOS)<br \/>\nSan Buenaventura vs. J.V.Gonz\u00e1lez<br \/>\nAtl\u00e9tico Chilecito vs. Independiente<br \/>\nLos Andes vs. Estrella Roja<br \/>\nNewell\u00b4s Old Boys vs. Defensores de la Plata<br \/>\nLos Chuyos vs. NOB de Sa\u00f1ogasta<br \/>\nUni\u00f3n vs. Anguin\u00e1n<br \/>\n7\u00ba FECHA<br \/>\nDefensores de la Plata vs. Uni\u00f3n<br \/>\nLos Chuyos vs. Independiente<br \/>\nAnguin\u00e1n vs. NOB de Sa\u00f1ogasta<br \/>\nJ.V.Gonz\u00e1lez vs. Los Andes<br \/>\nAtl\u00e9tico Chilecito vs. Newell\u00b4s Old Boys<br \/>\nEstrella Roja vs. San Buenaventura<br \/>\n8\u00ba FECHA<br \/>\nNewell\u00b4s Old Boys vs. J.V.Gonz\u00e1lez<br \/>\nIndependiente vs. Defensores de la Plata<br \/>\nNOB de Sa\u00f1ogasta vs. Los Chuyos<br \/>\nSan Buenaventura vs. Atl\u00e9tico Chilecito<br \/>\nUni\u00f3n vs. Estrella Roja<br \/>\nLos Andes vs. Anguin\u00e1n<br \/>\n9\u00ba FECHA<br \/>\nJ.V.Gonz\u00e1lez vs. San Buenaventura<br \/>\nAtl\u00e9tico Chilecito vs. Uni\u00f2n<br \/>\nLos Chuyos vs. Los Andes<br \/>\nEstrella Roja vs. Independiente<br \/>\nDefensores de la Plata vs. NOB de Sa\u00f1ogasta<br \/>\nAnguin\u00e1n vs. Newell\u00b4s Old Boys<br \/>\n10\u00ba FECHA<br \/>\nUni\u00f3n vs. J.V.Gonz\u00e1lez<br \/>\nLos Andes vs. Defensores de la Plata<br \/>\nSan Buenaventura vs. Anguin\u00e1n<br \/>\nIndependiente vs. Atl\u00e9tico Chilecito<br \/>\nNOB de Sa\u00f1ogasta vs. Estrella Roja<br \/>\nNewell\u00b4s Old Boys vs. Los Chuyos<br \/>\n11\u00ba FECHA<br \/>\nAtl\u00e9tico Chilecito vs. NOB de Sa\u00f1ogasta<br \/>\nDefensores de la Plata vs. Newell\u00b4s Old Boys<br \/>\nAnguin\u00e1n vs. Uni\u00f3n<br \/>\nJ.V.Gonz\u00e1lez vs. Independiente<br \/>\nEstrella Roja vs. Los Andes<br \/>\nLos Chuyos vs. San Buenaventura<br \/>\n12\u00ba FECHA<br \/>\nIndependiente vs. Anguin\u00e1n<br \/>\nUni\u00f3n vs. Los Chuyos<br \/>\nNewell\u00b4s Old Boys vs. Estrella Roja<br \/>\nSan Buenaventura vs. Defensores de la Plata<br \/>\nLos Andes vs. Atl\u00e9tico Chilecito<br \/>\nNOB de Sa\u00f1ogasta vs. J.V.Gonz\u00e1lez<br \/>\n13\u00ba FECHA (DESAF\u00cdOS)<br \/>\nAnguin\u00e1n vs. San Buenaventura<br \/>\nNOB de Sa\u00f1ogasta vs. Atl\u00e9tico Chilecito<br \/>\nJ.V.Gonz\u00e1lez vs. Uni\u00f3n<br \/>\nIndependiente vs. Los Chuyos<br \/>\nEstrella Roja vs. Newell\u00b4s Old Boys<br \/>\nDefensores de la Plata vs. Los Andes<br \/>\n14\u00ba FECHA<br \/>\nNewell\u00b4s Old Boys vs. Los Andes<br \/>\nUni\u00f3n vs. San Buenaventura<br \/>\nDefensores de la Plata vs. Estrella Roja<br \/>\nAtl\u00e9tico Chilecito vs. Estrella Roja<br \/>\nAtl\u00e9tico Chilecito vs. J.V.Gonz\u00e1lez<br \/>\nAnguin\u00e1n vs. Los Chuyos<br \/>\nNOB de Sa\u00f1ogasta vs. Independiente<br \/>\n15\u00ba FECHA<br \/>\nJ.V.Gonz\u00e1lez vs. Anguin\u00e1n<br \/>\nIndependiente vs. Uni\u00f3n<br \/>\nLos Andes vs. NOB de Sa\u00f1ogasta<br \/>\nEstrella Roja vs. Atl\u00e9tico Chilecito<br \/>\nLos Chuyos vs. Defensores de la Plata<br \/>\nSan Buenaventura vs. Newell\u00b4s Old Boys<br \/>\n16\u00ba FECHA<br \/>\nAtl\u00e9tico Chilecito vs. Defensores de la Plata<br \/>\nJ.V.Gonz\u00e1lez vs. Los Chuyos<br \/>\nAnguin\u00e1n vs. Estrella Roja<br \/>\nNOB de Sa\u00f1ogasta vs. San Buenaventura<br \/>\nNewell\u00b4s Old Boys vs. Uni\u00f3n<br \/>\nLos Andes vs. Independiente<br \/>\n17\u00ba FECHA<br \/>\nDefensores de la Plata vs. J.V.Gonz\u00e1lez<br \/>\nSan Buenaventura vs. Independiente<br \/>\nNewell\u00b4s Old Boys vs. NOB de Sa\u00f1ogasta<br \/>\nAtl\u00e9tico Chilecito vs. Anguin\u00e1n<br \/>\nEstrella Roja vs. Los Chuyos<br \/>\nUni\u00f3n vs. Los Andes<br \/>\n18\u00ba FECHA<br \/>\nLos Chuyos vs. Atl\u00e9tico Chilecito<br \/>\nIndependiente vs. Newell\u00b4s Old Boys<br \/>\nLos Andes vs. San Buenaventura<br \/>\nJ.V.Gonz\u00e1lez vs. Estrella Roja<br \/>\nDefensores de la Plata vs. Anguin\u00e1n<br \/>\nUni\u00f3n vs. NOB de Sa\u00f1ogasta<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los m\u00e1ximos goleadores del torneo en estas primeras fechas.<\/p>\n","protected":false},"author":2,"featured_media":10413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10412"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10413"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}