{"id":10382,"date":"2025-06-18T15:00:39","date_gmt":"2025-06-18T15:00:39","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=10382"},"modified":"2025-06-18T16:15:53","modified_gmt":"2025-06-18T16:15:53","slug":"futbol-femenino-tremenda-goleada-de-newells-y-triunfos-de-los-chuyos-y-defensores","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/06\/18\/futbol-femenino-tremenda-goleada-de-newells-y-triunfos-de-los-chuyos-y-defensores\/","title":{"rendered":"F\u00daTBOL FEMENINO: TREMENDA GOLEADA DE NEWELL\u00b4S, Y TRIUNFOS DE LOS CHUYOS Y DEFENSORES"},"content":{"rendered":"<p style=\"text-align: justify;\">Quinta jornada, concretada el pasado s\u00e1bado en canchas de ciudad y distritos del departamento.<!--more--><\/p>\n<p style=\"text-align: justify;\">Las chicas del f\u00fatbol femenino de la Liga Chilecite\u00f1a disputaron la fecha 5, \u00faltima de la ida del zona por zona.<br \/>\nPor la zona A, ganaron los dos punteros, ambos de visitante, Los Chuyos por 2 a 0 ante Atl\u00e9tico Chilecito, y Defensores de la Plata sobre Anguin\u00e1n, tambien por 2 a 0. En tanto que Estrella Roja derrot\u00f3 por 2 a 0 a J.V.Gonz\u00e1lez de Nonogasta.<br \/>\nEn la zona B, aplastante goleada de Newll\u00b4s Old Boys, fue por 9 a 0 ante Independiente, en tanto que los escoltas San Buenaventura y Los Andes, igualaron 0 a 0, y de visitante Uni\u00f3n de Malligasta se impuso por 1 a 0 ante NOB de la localidad de Sa\u00f1gasta.<\/p>\n<p style=\"text-align: justify;\"><strong>LAS POSICIONES<\/strong><br \/>\n<strong><em>ZONA \u201cA\u201d<\/em><\/strong><br \/>\nLos Chuyos (13)<br \/>\nDefensores (13)<br \/>\nEstrella Roja (7)<br \/>\nAnguin\u00e1n (4)<br \/>\nAtl\u00e9tico Chilecito (2)<br \/>\nJ.V.Gonz\u00e1lez (2)<\/p>\n<p style=\"text-align: justify;\"><em><strong>ZONA \u201cB\u201d<\/strong><\/em><br \/>\nNewell\u00b4s de Chilecito (15)<br \/>\nLos Andes (8)<br \/>\nSan Buenaventura (8)<br \/>\nUni\u00f3n (7)<br \/>\nNOB de Sa\u00f1ogasta (4)<br \/>\nIndependiente (0)<\/p>\n<p style=\"text-align: justify;\">\nPR\u00d3XIMA FECHA (6\u00ba)<\/p>\n<p style=\"text-align: justify;\">Se viene la fecha especial de los cl\u00e1sicos, que a su vez ser\u00e1 la primera jornada de las ocho fechas de los Interzonales. Juegan, Atl\u00e9tico Chilecito vs. Independiente, San Buenaventura vs. J.V.Gonz\u00e1lez, Los Andes vs. Estrella Roja.<br \/>\nNewell\u00b4s Old Boys vs. Defensores de la Plata; Los Chuyos vs. NOB de Sa\u00f1ogasta, y Uni\u00f3n vs. Anguin\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quinta jornada, concretada el pasado s\u00e1bado en canchas de ciudad y distritos del departamento.<\/p>\n","protected":false},"author":2,"featured_media":10383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10382"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10383"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}