{"id":10207,"date":"2025-06-09T01:00:48","date_gmt":"2025-06-09T01:00:48","guid":{"rendered":"https:\/\/chilecitosports.com.ar\/?p=10207"},"modified":"2025-06-09T01:00:48","modified_gmt":"2025-06-09T01:00:48","slug":"futbol-liga-4o-fecha-independiente-le-saco-el-invicto-al-santo-vichigasteno","status":"publish","type":"post","link":"https:\/\/chilecitosports.com.ar\/index.php\/2025\/06\/09\/futbol-liga-4o-fecha-independiente-le-saco-el-invicto-al-santo-vichigasteno\/","title":{"rendered":"F\u00daTBOL LIGA \u2013 4\u00ba FECHA: INDEPENDIENTE LE SAC\u00d3 EL INVICTO AL SANTO VICHIGASTE\u00d1O"},"content":{"rendered":"<p style=\"text-align: justify;\">Con tanto de Gaston Gaitan, el Rojo de local se impuso 1 a 0a a San Buenaventura de Vichigasta ganando por primera vez en el torneo y dejando sin invicto al Santo.<!--more--><\/p>\n<p style=\"text-align: justify;\">En la cancha del Rojo de calle Caminito, este domingo el local cosech\u00f3 el primer triunfo en el campeonato, y nada mas y nada menos que ante San Buenaventura de Vichigasta.<br \/>\nTras un primer tiempo parejo, de mas lucha y poco f\u00fatbol, donde ambos llegaron en un par de veces, pero sin aciertos concretos a los arcos. Lo relevante, fue la lesi\u00f3n en el hombro y salida de Alan Bajinay, el estratega del Santo.<br \/>\nEn el complemento, el Rojo saca ventaja a los 12 mintos, cuando la baja el capit\u00e1n Oliva, y llegando de atr\u00e1s Gast\u00f3n Gaitan anota, dejando sin chances al arquero Andrada; era el uno a cero para el local.<br \/>\nDe all\u00ed, la visita busc\u00f3 lo caminos, pero se le hizo complicado a los dirigidos por Soria, y el Rojo de a poco se fue afianzando, para llevarse un valioso triunfo, que el primero en la temporada. Juego que tuvo las expulsiones de tres jugadores, Reynoso y Troncoso (Independiente), y Ruarte (San Buenaventura).<br \/>\nEl Santo por lo contrario, pierde el invicto, y la punta de la zona B, que ahora est\u00e1 en manos de Los Andes, justamente su rival, la semana que viene en Vichigasta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con tanto de Gaston Gaitan, el Rojo de local se impuso 1 a 0a a San Buenaventura de Vichigasta ganando&hellip;<\/p>\n","protected":false},"author":2,"featured_media":10208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-10207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=10207"}],"version-history":[{"count":0,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/10207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media\/10208"}],"wp:attachment":[{"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=10207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=10207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chilecitosports.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=10207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}